{"id":2465,"date":"2013-03-20T13:38:59","date_gmt":"2013-03-20T12:38:59","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=2465"},"modified":"2014-08-19T23:09:23","modified_gmt":"2014-08-19T21:09:23","slug":"week-end-a-paris-2","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/2465-week-end-a-paris-2.html","title":{"rendered":"Week-end \u00e0 Paris"},"content":{"rendered":"<p>Nous avons pris la route vendredi soir pour un week-end \u00e0 Paris, top chrono 48h ! Nous y avons retrouv\u00e9 Marion &amp; G\u00e9rald. Nous en avons profit\u00e9 pour visiter Paris que les enfants connaissent peu finalement.<\/p>\n<p>Samedi, nous sommes all\u00e9s \u00e0 la Tour Eiffel, voici l&rsquo;\u00e9quipe de choc :<\/p>\n<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/equipe-tour-eiffel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2466\" title=\"equipe tour eiffel\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/equipe-tour-eiffel.jpg\" alt=\"\" width=\"600\" height=\"480\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/equipe-tour-eiffel.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/equipe-tour-eiffel-300x240.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Et comme on a peur de rien (et qu&rsquo;il n&rsquo;y avait presque pas de queue&#8230;), nous avons pris des billets pour le 2\u00e8me \u00e9tage, par les escaliers ! Les cocos ont eux aussi mont\u00e9 les 704 marches, sans qu&rsquo;on les porte ! Louise a eu un peu le vertige dans les escaliers mais une fois en haut, \u00e7a allait ! Quelques photos plus tard, nous sommes redescendus, un peu frigorifi\u00e9s par le vent !<\/p>\n<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/tour-eiffel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2467\" title=\"tour eiffel\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/tour-eiffel.jpg\" alt=\"\" width=\"600\" height=\"480\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/tour-eiffel.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/tour-eiffel-300x240.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Nous sommes ensuite all\u00e9s au restaurant f\u00eater l&rsquo;anniversaire de Franck.<\/p>\n<p>Puis direction Notre-Dame de Paris :<\/p>\n<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/notre-dame.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2468\" title=\"notre dame\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/notre-dame.jpg\" alt=\"\" width=\"600\" height=\"480\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/notre-dame.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/notre-dame-300x240.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Apr\u00e8s quelques minutes de queue, nous avons voir l&rsquo;int\u00e9rieur de la cath\u00e9drale, grandiose.<\/p>\n<p>Le Dimanche, nous avions RDV \u00e0 la Cit\u00e9 des Sciences \u00e0 la Villette pour une s\u00e9ance \u00e0 la Cit\u00e9 des Enfants avec mes copines de Paris. Emilie &amp; sa fille Camille, blondinette de 4 ans. M\u00e9lanie et Ronald et leurs enfants Faustine &amp; Malo bient\u00f4t 6ans et Lisa 7 mois :<\/p>\n<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/copines1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2475\" title=\"copines\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/copines1.jpg\" alt=\"\" width=\"600\" height=\"475\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/copines1.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/copines1-300x237.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Apr\u00e8s un petit Quick, nous avions r\u00e9serv\u00e9 pour la s\u00e9ance de 13h30 \u00e0 la Cit\u00e9 des Enfants :<\/p>\n<p><em>La Cit\u00e9 des enfants 2-7 ans s\u2019organise en cinq espaces th\u00e9matiques : Je me d\u00e9couvre, Je sais faire, Je me rep\u00e8re, J\u2019exp\u00e9rimente, Tous ensemble. Les trois premiers th\u00e8mes sont centr\u00e9s sur le d\u00e9veloppement de l\u2019enfant et ses facult\u00e9s corporelles, cognitives, spatiales. Les deux suivants proposent une ouverture au monde et aux autres. La Nouvelle Cit\u00e9 des enfants a conserv\u00e9 les activit\u00e9s qui ont fait la renomm\u00e9e de la Cit\u00e9 des enfants d\u2019origine, comme la Machine \u00e0 boule ou le Chantier !<\/em><\/p>\n<p><em>Un espace animation propose r\u00e9guli\u00e8rement des animations de 15 minutes pour plusieurs dizaines de visiteurs, enfants et adultes.<\/em><\/p>\n<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/cite1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/cite1.jpg\" alt=\"cite\" width=\"600\" height=\"480\" class=\"aligncenter size-full wp-image-4678\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/cite1.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/cite1-300x240.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>On a pass\u00e9 un super moment, les enfants ont exp\u00e9riment\u00e9 plein de choses, se sont bien entendus &amp; moi \u00e7a me fait tellement plaisir de retrouver mes cops de coll\u00e8ge&#8230; 20 ans plus tard !!!<\/p>\n<p>Le petit b\u00e9mol aura \u00e9t\u00e9 Marceau qui s&rsquo;est r\u00e9veill\u00e9 dimanche matin avec 39 de fi\u00e8vre &amp; a d\u00e9clar\u00e9 lundi une gastro chez la nounou, en m\u00eame temps que ses 2 coll\u00e8gues de chez nounou&#8230; et aujourd&rsquo;hui mercredi \u00e7a tra\u00eene encore&#8230; youpi &#8230; esp\u00e9rons que cela ne tourne pas !!!<\/p>\n<p>Bizzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons pris la route vendredi soir pour un week-end \u00e0 Paris, top chrono 48h ! Nous y avons retrouv\u00e9 Marion &amp; G\u00e9rald. Nous en avons profit\u00e9 pour visiter Paris que les enfants connaissent peu finalement. Samedi, nous sommes all\u00e9s \u00e0 la Tour Eiffel, voici l&rsquo;\u00e9quipe de choc : Et comme on a peur de &hellip; <\/p>\n","protected":false},"author":3,"featured_media":2466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voyages","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2013\/03\/equipe-tour-eiffel.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/2465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=2465"}],"version-history":[{"count":7,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/2465\/revisions"}],"predecessor-version":[{"id":4679,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/2465\/revisions\/4679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/2466"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=2465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=2465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=2465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}