{"id":3906,"date":"2014-03-18T20:59:33","date_gmt":"2014-03-18T19:59:33","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=3906"},"modified":"2020-03-08T20:51:50","modified_gmt":"2020-03-08T19:51:50","slug":"carnaval-a-anse","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/3906-carnaval-a-anse.html","title":{"rendered":"Carnaval 2014 \u00e0 Anse"},"content":{"rendered":"<p>Aujourd&rsquo;hui c&rsquo;\u00e9tait journ\u00e9e carnaval \u00e0 Anse avec une super m\u00e9t\u00e9o !!!<\/p>\n<p>Marceau s&rsquo;est d\u00e9guis\u00e9 d\u00e8s le matin, pour l&rsquo;\u00e9cole, en pomme ! Le th\u00e8me \u00e9tait impos\u00e9 : ce devait \u00eatre un d\u00e9guisement en lien avec l&rsquo;un des 5 sens ou 1 fruit ou l\u00e9gume ! Pas \u00e9vident !!!<br \/>\nJ&rsquo;ai eu peur qu&rsquo;il ne veuille mettre ses d\u00e9guisements de chevalier, buzz, woody ou cars mais non il \u00e9tait tout content en pomme !!! <\/p>\n<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/pomme.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/pomme.jpg\" alt=\"pomme\" width=\"600\" height=\"337\" class=\"aligncenter size-full wp-image-3907\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/pomme.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/pomme-300x168.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>A l&rsquo;\u00e9cole primaire les enfants devaient se d\u00e9guiser pour 13h30. Je n&rsquo;avais donc pas r\u00e9serv\u00e9 la cantine comme \u00e7a Louise a pu se changer et se pr\u00e9parer \u00e0 la maison en \u00ab\u00a0princesse des neiges\u00a0\u00bb !<\/p>\n<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/princesse.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/princesse-346x600.jpg\" alt=\"princesse\" width=\"346\" height=\"600\" class=\"aligncenter size-large wp-image-3908\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/princesse-346x600.jpg 346w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/princesse-173x300.jpg 173w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/princesse.jpg 600w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/><\/a><\/p>\n<p>Dans chacune des \u00e9coles il y avait un programme particulier : photos, petit go\u00fbter, chants&#8230;<\/p>\n<p>Et \u00e0 16h30 \u00e0 la sortie des \u00e9coles, il y a eu le d\u00e9fil\u00e9 dans les rues d&rsquo;Anse, o\u00f9 Louise a pu retrouv\u00e9 ses copines et Marceau ses copains ! Maman nous y a rejoint. Monsieur Carnaval a \u00e9t\u00e9 br\u00fbl\u00e9 sur la place principale, et ainsi f\u00eater l&rsquo;arriv\u00e9e du printemps.<\/p>\n<p>Puis de 18h00 \u00e0 20h00, tous les enfants du primaire (2 \u00e9coles !!!) \u00e9taient r\u00e9unis pour un grand bal dans la toute nouvelle salle Ansolia, sans les parents, avec des parents b\u00e9n\u00e9voles pour l&rsquo;organisation ! Il y avait un DJ, les enfants ont dans\u00e9 et visiblement ils se sont \u00e9clat\u00e9s sans les parents !!! Louise ne voulait plus rentrer !!! \u00e7a promet !!!   <\/p>\n<p>Bizzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/carna.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/carna.jpg\" alt=\"carna\" width=\"600\" height=\"337\" class=\"aligncenter size-full wp-image-3909\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/carna.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/carna-300x168.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui c&rsquo;\u00e9tait journ\u00e9e carnaval \u00e0 Anse avec une super m\u00e9t\u00e9o !!! Marceau s&rsquo;est d\u00e9guis\u00e9 d\u00e8s le matin, pour l&rsquo;\u00e9cole, en pomme ! Le th\u00e8me \u00e9tait impos\u00e9 : ce devait \u00eatre un d\u00e9guisement en lien avec l&rsquo;un des 5 sens ou 1 fruit ou l\u00e9gume ! Pas \u00e9vident !!! J&rsquo;ai eu peur qu&rsquo;il ne veuille mettre &hellip; <\/p>\n","protected":false},"author":3,"featured_media":3909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,8,9],"tags":[],"class_list":["post-3906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-louise","category-marceau","category-photos","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/carna.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/3906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=3906"}],"version-history":[{"count":2,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/3906\/revisions"}],"predecessor-version":[{"id":13864,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/3906\/revisions\/13864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/3909"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=3906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=3906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=3906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}