{"id":3915,"date":"2014-03-16T16:22:03","date_gmt":"2014-03-16T15:22:03","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=3915"},"modified":"2014-03-22T17:32:43","modified_gmt":"2014-03-22T16:32:43","slug":"35-ans-franck","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/3915-35-ans-franck.html","title":{"rendered":"35 ans Franck"},"content":{"rendered":"<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/belooga.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/belooga.jpg\" alt=\"belooga\" width=\"600\" height=\"337\" class=\"aligncenter size-full wp-image-3916\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/belooga.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/belooga-300x168.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Pour les 35 ans de Franck, nous nous sommes tous retrouv\u00e9s, apr\u00e8s organisation surprise, \u00e0 la brasserie Belooga \u00e0 Villefranche, qui est un nouveau resto qui vient d&rsquo;ouvrir. Le r\u00e9sultat de l&rsquo;association de 2 chefs dont Guy Lassausaie.<\/p>\n<p>Organisation un peu gal\u00e8re car au d\u00e9part je voulais un autre resto mais qui aurait visiblement ferm\u00e9 donc c&rsquo;est maman qui a pu me faire la r\u00e9servation de celui-ci en cachette, pendant que nous \u00e9tions au ski.<\/p>\n<p>Nous \u00e9tions 11 adultes et 6 enfants : nos 2 familles (pas tout le monde malheureusement&#8230;) et la famille Morard.<\/p>\n<p>Resto assez classe, cuisine raffin\u00e9e, on a tr\u00e8s bien mang\u00e9, en quantit\u00e9 raisonnable. Ils ont \u00e9t\u00e9 aussi sympa avec les enfants qui avaient un peu la bougeotte : plats adapt\u00e9s, servis rapidement, un DVD sur une immense t\u00e9l\u00e9 dans un salon &#038; fromages blancs servis pendant le film !<\/p>\n<p>Le menu choisi \u00e9tait \u00e0 environ 25\u20ac par personne hors boissons.<\/p>\n<p>Voici le site si vous voulez jeter un coup d&rsquo;oeil : <a href=\"http:\/\/www.hotelicietla.com\/fr\/brasserie-belooga-guy-lassausaie-herve-raphanel-beaujolais.php#brasserie-belooga-guy-lassausaie-herve-raphanel-beaujolais.php\">clic-clic juste ici<\/a> <\/p>\n<p>Franck a \u00e9t\u00e9 bien g\u00e2t\u00e9 avec plusieurs soins \/ massages en institut, bon cadeaux, pull Ralph Lauren &#038; un saut en \u00e9lastique !<\/p>\n<p>L&rsquo;apr\u00e8s-midi tout le monde est venu \u00e0 la maison mais Franck &#038; Marceau sont partis rapidement pour aller au stade, en Jean Jaur\u00e8s, avec cocktail avant \/ apr\u00e8s match ! La fontaine de chocolat &#038; ses brochettes de fruits ont eu du succ\u00e8s visiblement&#8230;!<\/p>\n<p>Bizzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour les 35 ans de Franck, nous nous sommes tous retrouv\u00e9s, apr\u00e8s organisation surprise, \u00e0 la brasserie Belooga \u00e0 Villefranche, qui est un nouveau resto qui vient d&rsquo;ouvrir. Le r\u00e9sultat de l&rsquo;association de 2 chefs dont Guy Lassausaie. Organisation un peu gal\u00e8re car au d\u00e9part je voulais un autre resto mais qui aurait visiblement ferm\u00e9 &hellip; <\/p>\n","protected":false},"author":3,"featured_media":3916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photos","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/03\/belooga.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/3915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=3915"}],"version-history":[{"count":1,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/3915\/revisions"}],"predecessor-version":[{"id":3917,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/3915\/revisions\/3917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/3916"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=3915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=3915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=3915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}