{"id":4010,"date":"2014-04-26T23:00:38","date_gmt":"2014-04-26T21:00:38","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=4010"},"modified":"2014-04-28T14:05:51","modified_gmt":"2014-04-28T12:05:51","slug":"concert-de-stromae-2","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/4010-concert-de-stromae-2.html","title":{"rendered":"Concert de STROMAE"},"content":{"rendered":"<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/04\/STROMAE_2630534157380120102.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/04\/STROMAE_2630534157380120102.jpg\" alt=\"STROMAE_2630534157380120102\" width=\"150\" height=\"193\" class=\"alignleft size-full wp-image-4011\" \/><\/a><\/p>\n<p>Ce soir nous \u00e9tions avec Franck au concert de STROMAE \u00e0 la Halle Tony Garnier. Une grosse rad\u00e9e de la voiture \u00e0 la salle de concert, plus de places r\u00e9serv\u00e9es dans la zone SAMU (pour les femmes enceintes) \u00e0 notre arriv\u00e9e, mais finalement on a trouv\u00e9 2 places pas bien loin donc \u00e7a changeait pas grand chose ! Un concert top, hyper \u00e9nergique &#038; un STROMAE bondissant, des d\u00e9cors, des lumi\u00e8res superbes, des chor\u00e9 qui le caract\u00e9risent bien mais  pas essouffl\u00e9 pour un sou, il \u00e9tait en live !<\/p>\n<p>Bon moi j&rsquo;ai pas trop boug\u00e9, je suis rest\u00e9e assise mais bon j&rsquo;ai chant\u00e9 !<\/p>\n<p>Merci Maman pour la garde des enfants ! \ud83d\ude09<\/p>\n<p>Bizzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce soir nous \u00e9tions avec Franck au concert de STROMAE \u00e0 la Halle Tony Garnier. Une grosse rad\u00e9e de la voiture \u00e0 la salle de concert, plus de places r\u00e9serv\u00e9es dans la zone SAMU (pour les femmes enceintes) \u00e0 notre arriv\u00e9e, mais finalement on a trouv\u00e9 2 places pas bien loin donc \u00e7a changeait pas &hellip; <\/p>\n","protected":false},"author":3,"featured_media":4011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-4010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adeline","category-loisirs","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2014\/04\/STROMAE_2630534157380120102.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/4010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=4010"}],"version-history":[{"count":3,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/4010\/revisions"}],"predecessor-version":[{"id":4014,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/4010\/revisions\/4014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/4011"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=4010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=4010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=4010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}