{"id":584,"date":"2010-10-22T19:27:54","date_gmt":"2010-10-22T19:27:54","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=584"},"modified":"2020-04-18T09:44:16","modified_gmt":"2020-04-18T07:44:16","slug":"louise-peint","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/584-louise-peint.html","title":{"rendered":"Louise peint&#8230;"},"content":{"rendered":"<p align=center><!-- s9ymdb:658 --><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15923\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/louisepeint.jpg\" width=\"352\" height=\"600\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/louisepeint.jpg 352w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/louisepeint-332x566.jpg 332w\" sizes=\"auto, (max-width: 352px) 100vw, 352px\" \/> <\/p>\n<p>L&rsquo;apr\u00e8s-midi si je demande \u00e0 Louise ce qu&rsquo;on fait au r\u00e9veil de la sieste, en ce moment, 9 fois sur 10 , c&rsquo;est de la PEINTURE ! Grande passion du moment ! Et m\u00eame mercredi chez Mam\u00e9 avec Auxence, pas manqu\u00e9 : peinture ! Comme vous le voyez c&rsquo;est un peu plus fourni que le coloriage ! Et elle a d\u00e9couvert la peinture noire : elle en a mis de partout ! <\/p>\n<p>Notre collection d&rsquo;oeuvres d&rsquo;art s&rsquo;agrandit dangereusement !!! Va falloir bient\u00f4t ouvrir une galerie !!! \ud83d\ude09<\/p>\n<p>Bizzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n<p>NB : En vacances \u00ab\u00a0polaires\u00a0\u00bb (comme elle dit !) pour 10 jours, Louise a ramen\u00e9 toute fi\u00e8re son classeur de l&rsquo;\u00e9cole ! On y a trouv\u00e9 un trombi avec tous les enfants de la classe, les comptines apprises, les premiers exercices avec consignes (bien respect\u00e9es sauf un exercice o\u00f9 il fallait colorier uniquement les pommes, et chez nous tous les fruits ont \u00e9t\u00e9 gribouill\u00e9s&#8230; donc on a eu un \u00ab\u00a0faux\u00a0\u00bb, le reste est juste&#8230; on est sauv\u00e9s ! \ud83d\ude09 Il y a aussi des photocopies de photos o\u00f9 l&rsquo;on voit Louise participer \u00e0 la r\u00e9alisation du gateau aux pommes. Je ne pensais pas qu&rsquo;ils cuisinaient \u00e0 l&rsquo;\u00e9cole&#8230; Et le d\u00e9but d&rsquo;apprentissage du bonhomme, qui est pour l&rsquo;instant chez nous, un petit tas de gribouillis ! Affaire \u00e0 suivre !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;apr\u00e8s-midi si je demande \u00e0 Louise ce qu&rsquo;on fait au r\u00e9veil de la sieste, en ce moment, 9 fois sur 10 , c&rsquo;est de la PEINTURE ! Grande passion du moment ! Et m\u00eame mercredi chez Mam\u00e9 avec Auxence, pas manqu\u00e9 : peinture ! Comme vous le voyez c&rsquo;est un peu plus fourni que le &hellip; <\/p>\n","protected":false},"author":3,"featured_media":15923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-louise","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/louisepeint.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=584"}],"version-history":[{"count":1,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/584\/revisions"}],"predecessor-version":[{"id":15924,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/584\/revisions\/15924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/15923"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}