{"id":599,"date":"2010-11-24T17:04:27","date_gmt":"2010-11-24T16:04:27","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=599"},"modified":"2020-04-18T09:44:09","modified_gmt":"2020-04-18T07:44:09","slug":"noel-cest-dans-un-mois","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/599-noel-cest-dans-un-mois.html","title":{"rendered":"No\u00ebl &#8230; c&rsquo;est dans un mois !"},"content":{"rendered":"<p align=center><!-- s9ymdb:673 --><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15895\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/lettre.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/lettre.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/lettre-332x221.jpg 332w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Sans rire, dans un mois c&rsquo;est No\u00ebl ! Il \u00e9tait donc temps pour Louise &#038; Marceau de faire leurs listes et de la poster histoire qu&rsquo;il puisse se pr\u00e9parer, ce P\u00e8re No\u00ebl !<\/p>\n<p>Louise a d\u00e9coup\u00e9 avec plaisir des tonnes et des tonnes de jouets donc on a du s\u00e9lectionner pour la liste ! Et elle a aussi d\u00e9coup\u00e9 pour Marceau ! Et \u00e7a y est, c&rsquo;est post\u00e9 ! Nous attendons sa r\u00e9ponse !!!<\/p>\n<p>La photo est petite donc voici en vrac ce qu&rsquo;elle a retenu en dernier recours : le Crocogolf, l&rsquo;Oeuf a dit, des patins \u00e0 roulettes, la princesse Raiponce avec cheveux \u00e0 tresser, Barbie &#038; son cheval, un d\u00e9guisement de princesse, un appareil photo num\u00e9rique (mais bien s\u00fbr), un grand Buzz, un ordinateur de Toy Story, une guitare, un puzzle avec les lettres de l&rsquo;alphabet, des tunnels pour Zhu zhu Pets !<\/p>\n<p>Et pour Marceau : une gigoteuse trop jolie (mais qu&rsquo;on a pas en photo), un chariot en bois avec cubes \u00e0 pousser, un crabe de bain, une voiture en bois, un \u00ab\u00a0b\u00e9b\u00e9 pilote\u00a0\u00bb, un \u00ab\u00a0b\u00e9b\u00e9 karaok\u00e9\u00a0\u00bb, un livre musical, mon 1er circuit avec voiture looping et un porteur en bois type voiture ou moto !<\/p>\n<p>Voili voilou&#8230; bon ben y&rsquo;a plus qu&rsquo;\u00e0 gagner au loto P\u00e8re No\u00ebl si tout le monde a des listes pareilles !!!<\/p>\n<p>Bizzzzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sans rire, dans un mois c&rsquo;est No\u00ebl ! Il \u00e9tait donc temps pour Louise &#038; Marceau de faire leurs listes et de la poster histoire qu&rsquo;il puisse se pr\u00e9parer, ce P\u00e8re No\u00ebl ! Louise a d\u00e9coup\u00e9 avec plaisir des tonnes et des tonnes de jouets donc on a du s\u00e9lectionner pour la liste ! Et &hellip; <\/p>\n","protected":false},"author":3,"featured_media":15895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-louise","category-marceau","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/lettre.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":2,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/599\/revisions"}],"predecessor-version":[{"id":15896,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/599\/revisions\/15896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/15895"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}