{"id":645,"date":"2011-02-20T17:25:57","date_gmt":"2011-02-20T16:25:57","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=645"},"modified":"2020-04-18T09:46:11","modified_gmt":"2020-04-18T07:46:11","slug":"a-9mois-je-suis-coquin-parfois","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/645-a-9mois-je-suis-coquin-parfois.html","title":{"rendered":"A 9mois, je suis coquin parfois !"},"content":{"rendered":"<p align=center><!-- s9ymdb:721 --><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16000\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/neufmois.jpg\" width=\"600\" height=\"352\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/neufmois.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/neufmois-332x195.jpg 332w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Notre petit Marceau f\u00eate ses 9 mois aujourd&rsquo;hui. Le temps passe vite&#8230; trop vite !<\/p>\n<p>Nous avons RDV demain matin chez le p\u00e9diatre donc nous en saurons plus sur ses mensurations.<\/p>\n<p>La bonne nouvelle c&rsquo;est que toute la maison est gu\u00e9rie&#8230; pourvu que \u00e7a dure surtout que nous partons bient\u00f4t en vacances&#8230;<\/p>\n<p>En tout cas pour notre petit gars, tout va bien ! Il change beaucoup en ce moment : il devient coquin, voit ce qui nous fait rire &#038; cherche \u00e0 amuser la galerie !<\/p>\n<p>Il tient maintenant bien assis. Il ne d\u00e9place pas encore mais commence \u00e0 chercher le 4 pattes, il prend de plus en plus souvent la position &#038; a trouv\u00e9 la marche arri\u00e8re en mode \u00ab\u00a0je rampe\u00a0\u00bb.<\/p>\n<p>Il fait toujours un peu de trotteur, \u00e0 vitesse grand V. Il fonce directement sur tout ce qui est interdit, notamment les plantes, en rigolant !!! \u00e7a promet&#8230; On abuse toutefois pas du trotteur car nous avons senti 2 soirs de suite craquer ses genoux mais le kin\u00e9 n&rsquo;a rien vu de sp\u00e9cial donc le trotteur \u00e0 petites doses&#8230;<\/p>\n<p>Sinon il mange toujours aussi bien &#038; est bien sociable. Tout se passe bien chez la nounou, chez qui c&rsquo;est d&rsquo;ailleurs la derni\u00e8re semaine.<\/p>\n<p>Rendez-vous le mois prochain !<\/p>\n<p>Bizzzz<\/p>\n<p>\u00a4 Adeline \u00a4 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre petit Marceau f\u00eate ses 9 mois aujourd&rsquo;hui. Le temps passe vite&#8230; trop vite ! Nous avons RDV demain matin chez le p\u00e9diatre donc nous en saurons plus sur ses mensurations. La bonne nouvelle c&rsquo;est que toute la maison est gu\u00e9rie&#8230; pourvu que \u00e7a dure surtout que nous partons bient\u00f4t en vacances&#8230; En tout cas &hellip; <\/p>\n","protected":false},"author":3,"featured_media":16000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marceau","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/neufmois.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=645"}],"version-history":[{"count":2,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/645\/revisions"}],"predecessor-version":[{"id":16001,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/645\/revisions\/16001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/16000"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}