{"id":747,"date":"2011-07-19T20:52:00","date_gmt":"2011-07-19T18:52:00","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=747"},"modified":"2020-04-18T09:48:00","modified_gmt":"2020-04-18T07:48:00","slug":"louise-romeo-marceau-anae","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/747-louise-romeo-marceau-anae.html","title":{"rendered":"Louise &#038; Rom\u00e9o, Marceau &#038; Ana\u00e9 !"},"content":{"rendered":"<p align=center><!-- s9ymdb:828 --><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16279\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/jura.jpg\" width=\"600\" height=\"480\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/jura.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/jura-332x266.jpg 332w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>La m\u00e9t\u00e9o de ce mois de juillet ne nous facilite pas les choses !!!<\/p>\n<p>Aujourd&rsquo;hui nous avions pr\u00e9vu, avec ma copine Marion (amiti\u00e9 issue de notre forum&#8230;) de se retrouver dans le Jura pour une petite journ\u00e9e avec les enfants au bord du Lac de Chalain&#8230; oui h\u00e9 bien non !!! Vu ce qu&rsquo;il tombait ce matin m\u00eame nous avons d\u00e9cid\u00e9 de changer nos plans, et de prendre notre plan B : rdv \u00e0 Lons le Saunier !<\/p>\n<p>Sur les conseils de Lolotte, nous avons \u00e9t\u00e9 visit\u00e9 la Maison de la Vache qui rit : des petits jeux interactifs tout au long de la visite cr\u00e9ent un fil conducteur pour les enfants. Sympa sans plus.<\/p>\n<p>Puis un petit Mac do &#038; apr\u00e8s avoir men\u00e9 notre enqu\u00eate au Mac do pour savoir quoi faire avec des enfants avec cette m\u00e9t\u00e9o : on nous a conseill\u00e9 le kid park, espace de jeux (balles, toboggans, gros l\u00e9go&#8230;) en int\u00e9rieur ! Nickel !<\/p>\n<p>Nous avons donc mis nos 4 petits, hop, dans les jeux !<\/p>\n<p>Louise et Rom\u00e9o sont tous les 2 n\u00e9s en Juillet 2007 &#038; Marceau et Ana\u00e9 en Mai 2010 (avec 4 jours d&rsquo;\u00e9cart), donc c&rsquo;\u00e9tait nickel, ils en sont au m\u00eame stade de d\u00e9veloppement (m\u00eame si Marceau va bient\u00f4t faire 2 fois le poids d&rsquo;Ana\u00e9 !!!) et se sont tous bien entendus. On a m\u00eame pu papoter (un peu !).<\/p>\n<p>On a pass\u00e9 une tr\u00e8s bonne journ\u00e9e ! Et Louise ne voulait plus quitter Rom\u00e9o ! Oh Rom\u00e9o&#8230; ! \ud83d\ude09<\/p>\n<p>Dommage que vous habitiez si loin les copains !!! D\u00e9m\u00e9nagez plus proche de chez nous l&rsquo;ann\u00e9e prochaine !!!<\/p>\n<p>Bizzzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00e9t\u00e9o de ce mois de juillet ne nous facilite pas les choses !!! Aujourd&rsquo;hui nous avions pr\u00e9vu, avec ma copine Marion (amiti\u00e9 issue de notre forum&#8230;) de se retrouver dans le Jura pour une petite journ\u00e9e avec les enfants au bord du Lac de Chalain&#8230; oui h\u00e9 bien non !!! Vu ce qu&rsquo;il tombait &hellip; <\/p>\n","protected":false},"author":3,"featured_media":16279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-loisirs","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/jura.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=747"}],"version-history":[{"count":2,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/747\/revisions"}],"predecessor-version":[{"id":16280,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/747\/revisions\/16280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/16279"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}