{"id":774,"date":"2011-09-12T19:17:00","date_gmt":"2011-09-12T19:17:00","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=774"},"modified":"2020-04-18T09:47:48","modified_gmt":"2020-04-18T07:47:48","slug":"gazon-seme","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/774-gazon-seme.html","title":{"rendered":"Gazon sem\u00e9 !"},"content":{"rendered":"<p align=center><!-- s9ymdb:861 --><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16222\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/gazon.jpg\" width=\"480\" height=\"600\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/gazon.jpg 480w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/gazon-332x415.jpg 332w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Depuis le temps qu&rsquo;on l&rsquo;attendait, c&rsquo;est fait !!!<\/p>\n<p>Jeudi et vendredi dernier, est intervenu un paysagiste (<a href=\"http:\/\/www.paysagiste-sebjardins.com\/\"  title=\"Seb Jardins\">Seb Jardins<\/a>) pour notre terrain !<\/p>\n<p>Il a travaill\u00e9 la terre, b\u00each\u00e9, enlev\u00e9 les pierres puis mis une couche de 5 \u00e0 10cm, par endroit, de terre v\u00e9g\u00e9tale (compost). Puis il a nivel\u00e9 et griff\u00e9 le terrain, sem\u00e9 les graines de gazon et roul\u00e9 !<\/p>\n<p>Maintenant \u00e0 nous d&rsquo;en prendre soin et de l&rsquo;arroser, 2 fois par jour (matin et soir) pendant 15 jours, s&rsquo;il ne pleut pas.<\/p>\n<p>Mais on l&rsquo;a tellement attendu ce gazon, que ce n&rsquo;est m\u00eame pas une contrainte, on va le chouchouter le petit !<\/p>\n<p>On a \u00e9galement profit\u00e9 du paysagiste pour lui faire planter les 2 oliviers de notre cr\u00e9maill\u00e8re, faire creuser une tranch\u00e9e pour le seuil du portail, et pr\u00e9par\u00e9 notre zone de massif de bambous, en haie, en limite de notre terrain. Il a b\u00each\u00e9, ouvert une tranch\u00e9e de 0.70cm de profondeur, plac\u00e9 une barri\u00e8re anti-rhizome (pour contenir les bambous l\u00e0 o\u00f9 on les veut !) &#038; nous avons r\u00e9cup\u00e9r\u00e9 des bambous chez les parents de Franck. Franck les a d\u00e9terr\u00e9s &#038; replant\u00e9s chez nous, esp\u00e9rons qu&rsquo;ils prennent !<\/p>\n<p>Voili voilou, le gazon a \u00e9t\u00e9 sem\u00e9 vendredi, et normalement en 7 jours, \u00e7a doit commenc\u00e9 \u00e0 sortir !<\/p>\n<p>Affaire \u00e0 suivre !<\/p>\n<p>Bizzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le temps qu&rsquo;on l&rsquo;attendait, c&rsquo;est fait !!! Jeudi et vendredi dernier, est intervenu un paysagiste (Seb Jardins) pour notre terrain ! Il a travaill\u00e9 la terre, b\u00each\u00e9, enlev\u00e9 les pierres puis mis une couche de 5 \u00e0 10cm, par endroit, de terre v\u00e9g\u00e9tale (compost). Puis il a nivel\u00e9 et griff\u00e9 le terrain, sem\u00e9 les &hellip; <\/p>\n","protected":false},"author":3,"featured_media":16222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maison","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2020\/04\/gazon.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=774"}],"version-history":[{"count":2,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/774\/revisions"}],"predecessor-version":[{"id":16223,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/774\/revisions\/16223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/16222"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}