{"id":8131,"date":"2017-05-18T18:42:12","date_gmt":"2017-05-18T16:42:12","guid":{"rendered":"http:\/\/adelineetfranck.fr\/blog\/?p=8131"},"modified":"2020-04-26T22:27:44","modified_gmt":"2020-04-26T20:27:44","slug":"chorale-a-ansolia","status":"publish","type":"post","link":"https:\/\/adelineetfranck.fr\/blog\/archives\/8131-chorale-a-ansolia.html","title":{"rendered":"Chorale \u00e0 Ansolia"},"content":{"rendered":"<p><a href=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2017\/07\/chorale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-8132\" src=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2017\/07\/chorale-620x421.jpg\" alt=\"chorale\" width=\"620\" height=\"421\" srcset=\"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2017\/07\/chorale-620x421.jpg 620w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2017\/07\/chorale-920x625.jpg 920w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2017\/07\/chorale-600x408.jpg 600w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2017\/07\/chorale-700x476.jpg 700w, https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2017\/07\/chorale-332x226.jpg 332w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p>Encore un tr\u00e8s beau spectacle musical des enfants de l&rsquo;\u00e9cole primaire de Ren\u00e9 Cassin, donc Louise et Marceau, ce soir \u00e0 la salle d&rsquo;Ansolia !<\/p>\n<p>Bizzzz<\/p>\n<p>\u00a4 Adeline \u00a4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encore un tr\u00e8s beau spectacle musical des enfants de l&rsquo;\u00e9cole primaire de Ren\u00e9 Cassin, donc Louise et Marceau, ce soir \u00e0 la salle d&rsquo;Ansolia ! Bizzzz \u00a4 Adeline \u00a4<\/p>\n","protected":false},"author":3,"featured_media":8132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-8131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-louise","category-marceau","latest_post"],"jetpack_featured_media_url":"https:\/\/adelineetfranck.fr\/blog\/wp-content\/uploads\/2017\/07\/chorale.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/8131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/comments?post=8131"}],"version-history":[{"count":2,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/8131\/revisions"}],"predecessor-version":[{"id":16895,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/posts\/8131\/revisions\/16895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media\/8132"}],"wp:attachment":[{"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/media?parent=8131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/categories?post=8131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adelineetfranck.fr\/blog\/wp-json\/wp\/v2\/tags?post=8131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}